{"id":1339,"date":"2013-10-31T21:30:00","date_gmt":"2013-10-31T21:30:00","guid":{"rendered":"https:\/\/awta.swim.net.au\/news\/key-test-data-summary-for-october-2013\/"},"modified":"2013-10-31T21:30:00","modified_gmt":"2013-10-31T21:30:00","slug":"key-test-data-summary-for-october-2013","status":"publish","type":"news","link":"https:\/\/awta.com.au\/fr\/news\/key-test-data-summary-for-october-2013\/","title":{"rendered":"R\u00e9sum\u00e9 des donn\u00e9es des tests cl\u00e9s pour octobre 2013"},"content":{"rendered":"<p style=\"margin: 6pt 0cm 0pt;\" class=\"NewsletterParagraph\">Les comparaisons mensuelles des lots totaux, des balles et du poids pour octobre 2013 par rapport \u00e0 la m\u00eame p\u00e9riode de la saison derni\u00e8re sont respectivement de +4,8%, +3,0% et +3,3%.<\/p>\n<p style=\"margin: 6pt 0cm 0pt;\" class=\"NewsletterParagraph\"><span class=\"doc_image\"><span class=\"doc_image\"><span class=\"doc_image\"><span class=\"doc_image\">Voici les comparaisons progressives du nombre total de lots, de balles et du poids pour la p\u00e9riode de juillet 2013 \u00e0 octobre 2013 par rapport \u00e0 la m\u00eame p\u00e9riode de la saison pr\u00e9c\u00e9dente\u00a0: <br \/>+1,4%, +0,9% et +1,3% respectivement.<\/span><\/span><\/span><\/span><\/p>\n<p style=\"margin: 6pt 0cm 0pt;\" class=\"NewsletterParagraph\">Progressivement, AWTA Ltd a test\u00e9 125,0 mkg (millions de kilogrammes) cette saison, contre 123,4 mkg pour la m\u00eame p\u00e9riode la saison derni\u00e8re.<\/p>\n<p style=\"margin: 6pt 0cm 0pt;\" class=\"NewsletterParagraph\"><a href=\"https:\/\/awtawooltesting.com.au\/index.php\/en\/component\/edocman\/?task=document.download&amp;id=320\">Donn\u00e9es cl\u00e9s des tests \u2013 octobre 2013<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Les comparaisons mensuelles des lots totaux, des balles et du poids pour octobre 2013 par rapport \u00e0 la m\u00eame p\u00e9riode de la saison derni\u00e8re sont respectivement de +4,8%, +3,0% et +3,3%. Les progres...<\/p>","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"class_list":["post-1339","news","type-news","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Key Test Data Summary for October 2013 - AWTA Limited<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/awta.com.au\/fr\/news\/key-test-data-summary-for-october-2013\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Key Test Data Summary for October 2013 - AWTA Limited\" \/>\n<meta property=\"og:description\" content=\"The monthly comparisons of Total Lots, Bales and Weight for October 2013 compared with the same period last season are +4.8%, +3.0% and +3.3% respectively. The progres\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/awta.com.au\/fr\/news\/key-test-data-summary-for-october-2013\/\" \/>\n<meta property=\"og:site_name\" content=\"AWTA Limited\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/awta.com.au\\\/news\\\/key-test-data-summary-for-october-2013\\\/\",\"url\":\"https:\\\/\\\/awta.com.au\\\/news\\\/key-test-data-summary-for-october-2013\\\/\",\"name\":\"Key Test Data Summary for October 2013 - AWTA Limited\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/awta.com.au\\\/zh_cn\\\/#website\"},\"datePublished\":\"2013-10-31T21:30:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/awta.com.au\\\/news\\\/key-test-data-summary-for-october-2013\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/awta.com.au\\\/news\\\/key-test-data-summary-for-october-2013\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/awta.com.au\\\/news\\\/key-test-data-summary-for-october-2013\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/awta.com.au\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/awta.com.au\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Key Test Data Summary for October 2013\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/awta.com.au\\\/zh_cn\\\/#website\",\"url\":\"https:\\\/\\\/awta.com.au\\\/zh_cn\\\/\",\"name\":\"AWTA Limited\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/awta.com.au\\\/zh_cn\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/awta.com.au\\\/zh_cn\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/awta.com.au\\\/zh_cn\\\/#organization\",\"name\":\"AWTA Limited\",\"url\":\"https:\\\/\\\/awta.com.au\\\/zh_cn\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/awta.com.au\\\/zh_cn\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/awta.com.au\\\/app\\\/uploads\\\/2025\\\/06\\\/awta-default.png\",\"contentUrl\":\"https:\\\/\\\/awta.com.au\\\/app\\\/uploads\\\/2025\\\/06\\\/awta-default.png\",\"width\":768,\"height\":474,\"caption\":\"AWTA Limited\"},\"image\":{\"@id\":\"https:\\\/\\\/awta.com.au\\\/zh_cn\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00e9sum\u00e9 des donn\u00e9es de test cl\u00e9s pour octobre 2013 - AWTA Limited","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/awta.com.au\/fr\/news\/key-test-data-summary-for-october-2013\/","og_locale":"fr_FR","og_type":"article","og_title":"Key Test Data Summary for October 2013 - AWTA Limited","og_description":"The monthly comparisons of Total Lots, Bales and Weight for October 2013 compared with the same period last season are +4.8%, +3.0% and +3.3% respectively. The progres\u2026","og_url":"https:\/\/awta.com.au\/fr\/news\/key-test-data-summary-for-october-2013\/","og_site_name":"AWTA Limited","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/awta.com.au\/news\/key-test-data-summary-for-october-2013\/","url":"https:\/\/awta.com.au\/news\/key-test-data-summary-for-october-2013\/","name":"R\u00e9sum\u00e9 des donn\u00e9es de test cl\u00e9s pour octobre 2013 - AWTA Limited","isPartOf":{"@id":"https:\/\/awta.com.au\/zh_cn\/#website"},"datePublished":"2013-10-31T21:30:00+00:00","breadcrumb":{"@id":"https:\/\/awta.com.au\/news\/key-test-data-summary-for-october-2013\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/awta.com.au\/news\/key-test-data-summary-for-october-2013\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/awta.com.au\/news\/key-test-data-summary-for-october-2013\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/awta.com.au\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/awta.com.au\/news\/"},{"@type":"ListItem","position":3,"name":"Key Test Data Summary for October 2013"}]},{"@type":"WebSite","@id":"https:\/\/awta.com.au\/zh_cn\/#website","url":"https:\/\/awta.com.au\/zh_cn\/","name":"AWTA Limited","description":"","publisher":{"@id":"https:\/\/awta.com.au\/zh_cn\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/awta.com.au\/zh_cn\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/awta.com.au\/zh_cn\/#organization","name":"AWTA Limited","url":"https:\/\/awta.com.au\/zh_cn\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/awta.com.au\/zh_cn\/#\/schema\/logo\/image\/","url":"https:\/\/awta.com.au\/app\/uploads\/2025\/06\/awta-default.png","contentUrl":"https:\/\/awta.com.au\/app\/uploads\/2025\/06\/awta-default.png","width":768,"height":474,"caption":"AWTA Limited"},"image":{"@id":"https:\/\/awta.com.au\/zh_cn\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/awta.com.au\/fr\/wp-json\/wp\/v2\/news\/1339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/awta.com.au\/fr\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/awta.com.au\/fr\/wp-json\/wp\/v2\/types\/news"}],"wp:attachment":[{"href":"https:\/\/awta.com.au\/fr\/wp-json\/wp\/v2\/media?parent=1339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}